{"id":1037,"date":"2025-10-14T08:18:44","date_gmt":"2025-10-14T06:18:44","guid":{"rendered":"https:\/\/freezestylers.de\/?p=1037"},"modified":"2025-10-14T20:07:32","modified_gmt":"2025-10-14T18:07:32","slug":"creative-connect-2025","status":"publish","type":"post","link":"https:\/\/freezestylers.de\/en\/2025\/10\/14\/creative-connect-2025\/","title":{"rendered":"Creative Connect 2025"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Im Juli hatten wir die M\u00f6glichkeit, unser Setup an einer unfassbaren Location aufzubauen und zu demonstrieren: im Rahmen der 3D Messe Creative Connect thronten die Kameras \u00fcber dem Ufer des Bodensees, mitten in einer alten Werft.. viel malerischer wird es nicht mehr:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/freezestylers.de\/wordpress\/wp-content\/uploads\/2025\/10\/CC25__0001_IMG_6858.HEIC-Kopie-1024x1024.jpg\" alt=\"\" class=\"wp-image-1069\" srcset=\"https:\/\/freezestylers.de\/wordpress\/wp-content\/uploads\/2025\/10\/CC25__0001_IMG_6858.HEIC-Kopie-1024x1024.jpg 1024w, https:\/\/freezestylers.de\/wordpress\/wp-content\/uploads\/2025\/10\/CC25__0001_IMG_6858.HEIC-Kopie-300x300.jpg 300w, https:\/\/freezestylers.de\/wordpress\/wp-content\/uploads\/2025\/10\/CC25__0001_IMG_6858.HEIC-Kopie-150x150.jpg 150w, https:\/\/freezestylers.de\/wordpress\/wp-content\/uploads\/2025\/10\/CC25__0001_IMG_6858.HEIC-Kopie-768x768.jpg 768w, https:\/\/freezestylers.de\/wordpress\/wp-content\/uploads\/2025\/10\/CC25__0001_IMG_6858.HEIC-Kopie-12x12.jpg 12w, https:\/\/freezestylers.de\/wordpress\/wp-content\/uploads\/2025\/10\/CC25__0001_IMG_6858.HEIC-Kopie-1140x1140.jpg 1140w, https:\/\/freezestylers.de\/wordpress\/wp-content\/uploads\/2025\/10\/CC25__0001_IMG_6858.HEIC-Kopie-920x920.jpg 920w, https:\/\/freezestylers.de\/wordpress\/wp-content\/uploads\/2025\/10\/CC25__0001_IMG_6858.HEIC-Kopie-575x575.jpg 575w, https:\/\/freezestylers.de\/wordpress\/wp-content\/uploads\/2025\/10\/CC25__0001_IMG_6858.HEIC-Kopie-380x380.jpg 380w, https:\/\/freezestylers.de\/wordpress\/wp-content\/uploads\/2025\/10\/CC25__0001_IMG_6858.HEIC-Kopie-420x420.jpg 420w, https:\/\/freezestylers.de\/wordpress\/wp-content\/uploads\/2025\/10\/CC25__0001_IMG_6858.HEIC-Kopie-800x800.jpg 800w, https:\/\/freezestylers.de\/wordpress\/wp-content\/uploads\/2025\/10\/CC25__0001_IMG_6858.HEIC-Kopie-100x100.jpg 100w, https:\/\/freezestylers.de\/wordpress\/wp-content\/uploads\/2025\/10\/CC25__0001_IMG_6858.HEIC-Kopie.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Tough working conditions \ud83d\ude09<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Den Aufbau erledigten wir am Vorabend und da der Veranstaltungsort relativ frei zug\u00e4nglich war kamen wir sogar in den Genuss, die Nacht im Setup verbringen zu d\u00fcrfen. Frische Luft, das Ger\u00e4usch leichten Wellengangs im Ohr.. 1a!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Messetag gestaltete sich extrem kurzweilig. Als &#8222;Prop&#8220; diente uns eine h\u00fcbsche alte Vespa, die von den interessierten Versuchspersonen \u00e4u\u00dferst begeistert angenommen wurde. Durch einen bunten Mix aus Technik zeigen und erkl\u00e4ren, Demoaufnahmen machen und Ergebnisse diskutieren verging der Tag wie im Flug. Dank unserer Event-Pipeline konnten die G\u00e4ste Aufnahmen von sich machen und diese innerhalb weniger Minuten als gecroppte 3D Modelle, Roh-Modelle, einen fertigen Videoclip und als Video zum direkt am Handy selbst editieren erhalten. Das Event war ein voller Erfolg! Die Ergebnisse und R\u00fcckmeldungen waren super, unsere Pipeline hat trotz einiger technischer Premieren einwandfrei funktioniert und wir freuen uns schon 2026 hoffentlich wieder mit von der Partie zu sein! Hier eine Verbildlichung des Tages:<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video controls src=\"https:\/\/freezestylers.de\/Media\/Timelapse_CreativConnect.MP4\"><\/video><figcaption class=\"wp-element-caption\">Music: <a href=\"http:\/\/www.musicfox.com\/\">http:\/\/www.musicfox.com<\/a><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Im Juli hatten wir die M\u00f6glichkeit, unser Setup an einer unfassbaren Location aufzubauen und zu demonstrieren: im Rahmen der 3D Messe Creative Connect thronten die Kameras \u00fcber dem Ufer des [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1065,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1,43],"tags":[],"class_list":["post-1037","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-projects"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Creative Connect 2025 - Freezestylers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/freezestylers.de\/en\/2025\/10\/14\/creative-connect-2025\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Creative Connect 2025 - Freezestylers\" \/>\n<meta property=\"og:description\" content=\"Im Juli hatten wir die M\u00f6glichkeit, unser Setup an einer unfassbaren Location aufzubauen und zu demonstrieren: im Rahmen der 3D Messe Creative Connect thronten die Kameras \u00fcber dem Ufer des [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/freezestylers.de\/en\/2025\/10\/14\/creative-connect-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Freezestylers\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-14T06:18:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-14T18:07:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/freezestylers.de\/wordpress\/wp-content\/uploads\/2025\/10\/IMG_68611.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lars S.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lars S.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/freezestylers.de\\\/2025\\\/10\\\/14\\\/creative-connect-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/freezestylers.de\\\/2025\\\/10\\\/14\\\/creative-connect-2025\\\/\"},\"author\":{\"name\":\"Lars S.\",\"@id\":\"https:\\\/\\\/freezestylers.de\\\/#\\\/schema\\\/person\\\/ec95c7c5ddfff5e2aea251a645d421fb\"},\"headline\":\"Creative Connect 2025\",\"datePublished\":\"2025-10-14T06:18:44+00:00\",\"dateModified\":\"2025-10-14T18:07:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/freezestylers.de\\\/2025\\\/10\\\/14\\\/creative-connect-2025\\\/\"},\"wordCount\":212,\"publisher\":{\"@id\":\"https:\\\/\\\/freezestylers.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/freezestylers.de\\\/2025\\\/10\\\/14\\\/creative-connect-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/freezestylers.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/IMG_68611.jpg\",\"articleSection\":[\"Allgemein\",\"Projekte\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/freezestylers.de\\\/2025\\\/10\\\/14\\\/creative-connect-2025\\\/\",\"url\":\"https:\\\/\\\/freezestylers.de\\\/2025\\\/10\\\/14\\\/creative-connect-2025\\\/\",\"name\":\"Creative Connect 2025 - Freezestylers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/freezestylers.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/freezestylers.de\\\/2025\\\/10\\\/14\\\/creative-connect-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/freezestylers.de\\\/2025\\\/10\\\/14\\\/creative-connect-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/freezestylers.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/IMG_68611.jpg\",\"datePublished\":\"2025-10-14T06:18:44+00:00\",\"dateModified\":\"2025-10-14T18:07:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/freezestylers.de\\\/2025\\\/10\\\/14\\\/creative-connect-2025\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/freezestylers.de\\\/2025\\\/10\\\/14\\\/creative-connect-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/freezestylers.de\\\/2025\\\/10\\\/14\\\/creative-connect-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/freezestylers.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/IMG_68611.jpg\",\"contentUrl\":\"https:\\\/\\\/freezestylers.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/IMG_68611.jpg\",\"width\":1000,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/freezestylers.de\\\/2025\\\/10\\\/14\\\/creative-connect-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/freezestylers.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Creative Connect 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/freezestylers.de\\\/#website\",\"url\":\"https:\\\/\\\/freezestylers.de\\\/\",\"name\":\"Freezestylers\",\"description\":\"3D Yourself\",\"publisher\":{\"@id\":\"https:\\\/\\\/freezestylers.de\\\/#organization\"},\"alternateName\":\"FS 3D\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/freezestylers.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/freezestylers.de\\\/#organization\",\"name\":\"Freezestylers\",\"url\":\"https:\\\/\\\/freezestylers.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/freezestylers.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/freezestylers.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-logo_trans_wtext_lowres.png\",\"contentUrl\":\"https:\\\/\\\/freezestylers.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-logo_trans_wtext_lowres.png\",\"width\":1000,\"height\":156,\"caption\":\"Freezestylers\"},\"image\":{\"@id\":\"https:\\\/\\\/freezestylers.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/freezestylers.de\\\/#\\\/schema\\\/person\\\/ec95c7c5ddfff5e2aea251a645d421fb\",\"name\":\"Lars S.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39e354ab28a759e3c83d5c4f6af3d3d49bc37dfd25e27194978a402254bb55c9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39e354ab28a759e3c83d5c4f6af3d3d49bc37dfd25e27194978a402254bb55c9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39e354ab28a759e3c83d5c4f6af3d3d49bc37dfd25e27194978a402254bb55c9?s=96&d=mm&r=g\",\"caption\":\"Lars S.\"},\"url\":\"https:\\\/\\\/freezestylers.de\\\/en\\\/author\\\/lars\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Creative Connect 2025 - Freezestylers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/freezestylers.de\/en\/2025\/10\/14\/creative-connect-2025\/","og_locale":"en_US","og_type":"article","og_title":"Creative Connect 2025 - Freezestylers","og_description":"Im Juli hatten wir die M\u00f6glichkeit, unser Setup an einer unfassbaren Location aufzubauen und zu demonstrieren: im Rahmen der 3D Messe Creative Connect thronten die Kameras \u00fcber dem Ufer des [&hellip;]","og_url":"https:\/\/freezestylers.de\/en\/2025\/10\/14\/creative-connect-2025\/","og_site_name":"Freezestylers","article_published_time":"2025-10-14T06:18:44+00:00","article_modified_time":"2025-10-14T18:07:32+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/freezestylers.de\/wordpress\/wp-content\/uploads\/2025\/10\/IMG_68611.jpg","type":"image\/jpeg"}],"author":"Lars S.","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Lars S.","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/freezestylers.de\/2025\/10\/14\/creative-connect-2025\/#article","isPartOf":{"@id":"https:\/\/freezestylers.de\/2025\/10\/14\/creative-connect-2025\/"},"author":{"name":"Lars S.","@id":"https:\/\/freezestylers.de\/#\/schema\/person\/ec95c7c5ddfff5e2aea251a645d421fb"},"headline":"Creative Connect 2025","datePublished":"2025-10-14T06:18:44+00:00","dateModified":"2025-10-14T18:07:32+00:00","mainEntityOfPage":{"@id":"https:\/\/freezestylers.de\/2025\/10\/14\/creative-connect-2025\/"},"wordCount":212,"publisher":{"@id":"https:\/\/freezestylers.de\/#organization"},"image":{"@id":"https:\/\/freezestylers.de\/2025\/10\/14\/creative-connect-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/freezestylers.de\/wordpress\/wp-content\/uploads\/2025\/10\/IMG_68611.jpg","articleSection":["Allgemein","Projekte"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/freezestylers.de\/2025\/10\/14\/creative-connect-2025\/","url":"https:\/\/freezestylers.de\/2025\/10\/14\/creative-connect-2025\/","name":"Creative Connect 2025 - Freezestylers","isPartOf":{"@id":"https:\/\/freezestylers.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/freezestylers.de\/2025\/10\/14\/creative-connect-2025\/#primaryimage"},"image":{"@id":"https:\/\/freezestylers.de\/2025\/10\/14\/creative-connect-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/freezestylers.de\/wordpress\/wp-content\/uploads\/2025\/10\/IMG_68611.jpg","datePublished":"2025-10-14T06:18:44+00:00","dateModified":"2025-10-14T18:07:32+00:00","breadcrumb":{"@id":"https:\/\/freezestylers.de\/2025\/10\/14\/creative-connect-2025\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/freezestylers.de\/2025\/10\/14\/creative-connect-2025\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/freezestylers.de\/2025\/10\/14\/creative-connect-2025\/#primaryimage","url":"https:\/\/freezestylers.de\/wordpress\/wp-content\/uploads\/2025\/10\/IMG_68611.jpg","contentUrl":"https:\/\/freezestylers.de\/wordpress\/wp-content\/uploads\/2025\/10\/IMG_68611.jpg","width":1000,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/freezestylers.de\/2025\/10\/14\/creative-connect-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/freezestylers.de\/"},{"@type":"ListItem","position":2,"name":"Creative Connect 2025"}]},{"@type":"WebSite","@id":"https:\/\/freezestylers.de\/#website","url":"https:\/\/freezestylers.de\/","name":"Freezestylers","description":"3D Yourself","publisher":{"@id":"https:\/\/freezestylers.de\/#organization"},"alternateName":"FS 3D","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/freezestylers.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/freezestylers.de\/#organization","name":"Freezestylers","url":"https:\/\/freezestylers.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/freezestylers.de\/#\/schema\/logo\/image\/","url":"https:\/\/freezestylers.de\/wordpress\/wp-content\/uploads\/2024\/12\/cropped-logo_trans_wtext_lowres.png","contentUrl":"https:\/\/freezestylers.de\/wordpress\/wp-content\/uploads\/2024\/12\/cropped-logo_trans_wtext_lowres.png","width":1000,"height":156,"caption":"Freezestylers"},"image":{"@id":"https:\/\/freezestylers.de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/freezestylers.de\/#\/schema\/person\/ec95c7c5ddfff5e2aea251a645d421fb","name":"Lars S.","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/39e354ab28a759e3c83d5c4f6af3d3d49bc37dfd25e27194978a402254bb55c9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/39e354ab28a759e3c83d5c4f6af3d3d49bc37dfd25e27194978a402254bb55c9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/39e354ab28a759e3c83d5c4f6af3d3d49bc37dfd25e27194978a402254bb55c9?s=96&d=mm&r=g","caption":"Lars S."},"url":"https:\/\/freezestylers.de\/en\/author\/lars\/"}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/freezestylers.de\/en\/wp-json\/wp\/v2\/posts\/1037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/freezestylers.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/freezestylers.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/freezestylers.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/freezestylers.de\/en\/wp-json\/wp\/v2\/comments?post=1037"}],"version-history":[{"count":3,"href":"https:\/\/freezestylers.de\/en\/wp-json\/wp\/v2\/posts\/1037\/revisions"}],"predecessor-version":[{"id":1070,"href":"https:\/\/freezestylers.de\/en\/wp-json\/wp\/v2\/posts\/1037\/revisions\/1070"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/freezestylers.de\/en\/wp-json\/wp\/v2\/media\/1065"}],"wp:attachment":[{"href":"https:\/\/freezestylers.de\/en\/wp-json\/wp\/v2\/media?parent=1037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/freezestylers.de\/en\/wp-json\/wp\/v2\/categories?post=1037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/freezestylers.de\/en\/wp-json\/wp\/v2\/tags?post=1037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}